{"id":5362,"date":"2026-05-29T08:09:45","date_gmt":"2026-05-29T06:09:45","guid":{"rendered":"https:\/\/splaboratorija.rs\/blog\/"},"modified":"2026-05-29T08:12:34","modified_gmt":"2026-05-29T06:12:34","slug":"blog","status":"publish","type":"page","link":"https:\/\/splaboratorija.rs\/en\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5362\" class=\"elementor elementor-5362 elementor-5354\">\n\t\t\t\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-ac01b0d e-con-boxed e-con\" data-id=\"ac01b0d\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-dbe0f8f e-con-full e-con\" data-id=\"dbe0f8f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e53367f elementor-grid-1 elementor-posts--align-left elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"e53367f\" data-element_type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;pagination_type&quot;:&quot;load_more_infinite_scroll&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/splaboratorija.rs\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-posts.min.css\">\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5427 post type-post status-publish format-standard hentry category-blog-en\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/splaboratorija.rs\/en\/2026\/06\/11\/utvrdjivanje-spf-bez-volontera-trziste-kozmetike-usmerava-se-ka-novim-izazovima-i-trendovima\/\" >\n\t\t\t\tDetermining SPF without volunteers? The cosmetics market is directing towards new challenges and trends\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 11, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Until a few years ago, determination of SPF values \u200b\u200bwithout human testing was considered an almost unattainable goal \u2014 an idea for the future, not in everyday practice. Today, the<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/splaboratorija.rs\/en\/2026\/06\/11\/utvrdjivanje-spf-bez-volontera-trziste-kozmetike-usmerava-se-ka-novim-izazovima-i-trendovima\/\" aria-label=\"Read more about Determining SPF without volunteers? The cosmetics market is directing towards new challenges and trends\" >\n\t\t\tPro\u010ditaj vi\u0161e \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5392 post type-post status-publish format-standard hentry category-blog-en\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/splaboratorija.rs\/en\/2026\/06\/05\/ispitivanje-hrane-za-zivotinje-u-akreditovanoj-laboratoriji\/\" >\n\t\t\t\tAnimal feed testing in accredited laboratory\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJune 5, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Service description SP Laboratorija, as accredited laboratory, perform analyses of animal feed such as: SP Laboratoroija performs analyzes of nutrients, vitamins, minerals, amino acids, harmful substances and other parameters important<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/splaboratorija.rs\/en\/2026\/06\/05\/ispitivanje-hrane-za-zivotinje-u-akreditovanoj-laboratoriji\/\" aria-label=\"Read more about Animal feed testing in accredited laboratory\" >\n\t\t\tPro\u010ditaj vi\u0161e \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-5370 post type-post status-publish format-standard hentry category-blog-en\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/splaboratorija.rs\/en\/2026\/05\/29\/ispitivanje-hrane-u-akreditovanoj-laboratoriji\/\" >\n\t\t\t\tFood testing in accredited laboratory\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tMay 29, 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>What is meant by the term food? According to the Law on Food Safety (&#8220;Official Gazette of RS&#8221;, no. 41\/2009 and 17\/2019) food is any substance or product, processed, partially<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/splaboratorija.rs\/en\/2026\/05\/29\/ispitivanje-hrane-u-akreditovanoj-laboratoriji\/\" aria-label=\"Read more about Food testing in accredited laboratory\" >\n\t\t\tPro\u010ditaj vi\u0161e \u00bb\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t<\/span>\n\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5362","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/pages\/5362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/comments?post=5362"}],"version-history":[{"count":3,"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/pages\/5362\/revisions"}],"predecessor-version":[{"id":5365,"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/pages\/5362\/revisions\/5365"}],"wp:attachment":[{"href":"https:\/\/splaboratorija.rs\/en\/wp-json\/wp\/v2\/media?parent=5362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}